{"id":2671,"date":"2018-12-08T22:00:00","date_gmt":"2018-12-08T22:00:00","guid":{"rendered":"http:\/\/relaunch2025.zeitenspiegel.de\/projekte\/was-geschah-mit-bruno-manser\/"},"modified":"2025-12-22T13:17:04","modified_gmt":"2025-12-22T13:17:04","slug":"what-happened-to-bruno-manser","status":"publish","type":"projekte","link":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/","title":{"rendered":"What happened to Bruno Manser?"},"content":{"rendered":"<p>Author <a href=\"\/en\/team\/carsten-stormer\/\">Carsten Stormer<\/a><br>Appeared in \u201eGeo,\u201c 12\/18<\/p>\n\n\n\n<p>A Swiss activist disappeared 18 years ago in Borneo. He had helped the Penan forest nomads resist the deforestation of their habitat. The Penan's fight to preserve one of Earth's oldest rainforests continues to this day. Bruno Manser's legacy helps them in this struggle \u2013 but the mystery of his disappearance remains unsolved.<\/p>\n\n\n\n<p><a class=\"publication-link\" href=\"\/en\/publications\/what-happened-to-bruno-manser\/\">For Publication \u00bb<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Autor Carsten StormerErschienen in &#8222;Geo&#8220;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen [&hellip;]<\/p>\n","protected":false},"featured_media":2672,"parent":0,"menu_order":0,"template":"","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"tags":[13,9],"class_list":["post-2671","projekte","type-projekte","status-publish","has-post-thumbnail","hentry","tag-carsten-stormer","tag-reportage"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Autor Carsten StormerErschienen in &quot;Geo&quot;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Zeitenspiegel Reportagen \u2192 Die Agentur f\u00fcr Reportagen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen\" \/>\n\t\t<meta property=\"og:description\" content=\"Autor Carsten StormerErschienen in &quot;Geo&quot;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t\t<meta property=\"og:image:height\" content=\"42\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-12-08T22:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-22T13:17:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Zeitenspiegel\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Autor Carsten StormerErschienen in &quot;Geo&quot;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"name\":\"Reportage\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"position\":2,\"name\":\"Reportage\",\"item\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#listItem\",\"name\":\"Was geschah mit Bruno Manser?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#listItem\",\"position\":3,\"name\":\"Was geschah mit Bruno Manser?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"name\":\"Reportage\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#organization\",\"name\":\"Zeitenspiegel Reportagen\",\"description\":\"Die Agentur f\\u00fcr Reportagen\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/zeitenspiegel-reportagen-logo.svg\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#organizationLogo\",\"width\":516,\"height\":42,\"caption\":\"Zeitenspiegel Reportagen Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Zeitenspiegel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zeitenspiegel\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#webpage\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/\",\"name\":\"Was geschah mit Bruno Manser? \\u2192 Zeitenspiegel Reportagen\",\"description\":\"Autor Carsten StormerErschienen in \\\"Geo\\\", 12\\\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\\u00fcr die Bewahrung eines der \\u00e4ltesten Regenw\\u00e4lder der Erde dauert bis heute an. Das Verm\\u00e4chtnis Bruno Mansers hilft ihnen\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cs_manser_teaser.jpg\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#mainImage\",\"width\":1920,\"height\":1280,\"caption\":\"CS_Manser_Teaser\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/was-geschah-mit-bruno-manser\\\/#mainImage\"},\"datePublished\":\"2018-12-08T22:00:00+00:00\",\"dateModified\":\"2025-12-22T13:17:04+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/\",\"name\":\"Zeitenspiegel Reportagen\",\"alternateName\":\"Zeitenspiegel\",\"description\":\"Die Agentur f\\u00fcr Reportagen\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen","description":"Autor Carsten StormerErschienen in \"Geo\", 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen","canonical_url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.zeitenspiegel.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","name":"Reportage"}},{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","position":2,"name":"Reportage","item":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#listItem","name":"Was geschah mit Bruno Manser?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#listItem","position":3,"name":"Was geschah mit Bruno Manser?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","name":"Reportage"}}]},{"@type":"Organization","@id":"https:\/\/www.zeitenspiegel.de\/en\/#organization","name":"Zeitenspiegel Reportagen","description":"Die Agentur f\u00fcr Reportagen","url":"https:\/\/www.zeitenspiegel.de\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#organizationLogo","width":516,"height":42,"caption":"Zeitenspiegel Reportagen Logo"},"image":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Zeitenspiegel\/","https:\/\/www.instagram.com\/zeitenspiegel\/"]},{"@type":"WebPage","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#webpage","url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/","name":"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen","description":"Autor Carsten StormerErschienen in \"Geo\", 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/07\/cs_manser_teaser.jpg","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#mainImage","width":1920,"height":1280,"caption":"CS_Manser_Teaser"},"primaryImageOfPage":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/#mainImage"},"datePublished":"2018-12-08T22:00:00+00:00","dateModified":"2025-12-22T13:17:04+00:00"},{"@type":"WebSite","@id":"https:\/\/www.zeitenspiegel.de\/en\/#website","url":"https:\/\/www.zeitenspiegel.de\/en\/","name":"Zeitenspiegel Reportagen","alternateName":"Zeitenspiegel","description":"Die Agentur f\u00fcr Reportagen","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Zeitenspiegel Reportagen \u2192 Die Agentur f\u00fcr Reportagen","og:type":"article","og:title":"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen","og:description":"Autor Carsten StormerErschienen in &quot;Geo&quot;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen","og:url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/","og:image":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","og:image:secure_url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","og:image:width":517,"og:image:height":42,"article:published_time":"2018-12-08T22:00:00+00:00","article:modified_time":"2025-12-22T13:17:04+00:00","article:publisher":"https:\/\/www.facebook.com\/Zeitenspiegel\/","twitter:card":"summary_large_image","twitter:title":"Was geschah mit Bruno Manser? \u2192 Zeitenspiegel Reportagen","twitter:description":"Autor Carsten StormerErschienen in &quot;Geo&quot;, 12\/18 Ein Schweizer Aktivist verschwand vor 18 Jahren auf Borneo. Er hatte den Waldnomaden vom Volk der Penan geholfen, sich gegen die Abholzung ihres Lebensraums zu wehren. Der Kampf der Penan f\u00fcr die Bewahrung eines der \u00e4ltesten Regenw\u00e4lder der Erde dauert bis heute an. Das Verm\u00e4chtnis Bruno Mansers hilft ihnen","twitter:image":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg"},"aioseo_meta_data":{"post_id":"2671","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-27 12:51:09","updated":"2025-12-22 13:19:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.zeitenspiegel.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/\" title=\"Reportage\">Reportage<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWas geschah mit Bruno Manser?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.zeitenspiegel.de\/en"},{"label":"Reportage","link":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/"},{"label":"Was geschah mit Bruno Manser?","link":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/was-geschah-mit-bruno-manser\/"}],"_links":{"self":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte"}],"about":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/types\/projekte"}],"version-history":[{"count":1,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte\/2671\/revisions"}],"predecessor-version":[{"id":8167,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte\/2671\/revisions\/8167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/media\/2672"}],"wp:attachment":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/tags?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}