{"id":2857,"date":"2014-08-31T22:00:00","date_gmt":"2014-08-31T22:00:00","guid":{"rendered":"http:\/\/relaunch2025.zeitenspiegel.de\/projekte\/die-truemmermaenner\/"},"modified":"2014-08-31T22:00:00","modified_gmt":"2014-08-31T22:00:00","slug":"die-truemmermaenner","status":"publish","type":"projekte","link":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/","title":{"rendered":"The Rubble Men"},"content":{"rendered":"<p>Author <a href=\"\/en\/team\/carsten-stormer\/\">Carsten Stormer<\/a><br \/>Published in \u201eNeon,\u201c 09\/2014<\/p>\n<p>Millions of Syrians are on the run. But what happens to those who stayed? In Aleppo, former fighters are trying to save what cannot be saved.<\/p>\n<p\/>","protected":false},"excerpt":{"rendered":"<p>Autor Carsten StormerErschienen in &#8222;Neon&#8220;, 09\/2014 Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.<\/p>","protected":false},"featured_media":2858,"parent":0,"menu_order":0,"template":"","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"tags":[13,9],"class_list":["post-2857","projekte","type-projekte","status-publish","has-post-thumbnail","hentry","tag-carsten-stormer","tag-reportage"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Autor Carsten StormerErschienen in &quot;Neon&quot;, 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Zeitenspiegel Reportagen \u2192 Die Agentur f\u00fcr Reportagen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen\" \/>\n\t\t<meta property=\"og:description\" content=\"Autor Carsten StormerErschienen in &quot;Neon&quot;, 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t\t<meta property=\"og:image:height\" content=\"42\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-31T22:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-31T22:00:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Zeitenspiegel\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Autor Carsten StormerErschienen in &quot;Neon&quot;, 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"name\":\"Reportage\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"position\":2,\"name\":\"Reportage\",\"item\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#listItem\",\"name\":\"Die Tr\\u00fcmmerm\\u00e4nner\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#listItem\",\"position\":3,\"name\":\"Die Tr\\u00fcmmerm\\u00e4nner\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/tag\\\/reportage\\\/#listItem\",\"name\":\"Reportage\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#organization\",\"name\":\"Zeitenspiegel Reportagen\",\"description\":\"Die Agentur f\\u00fcr Reportagen\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/zeitenspiegel-reportagen-logo.svg\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#organizationLogo\",\"width\":516,\"height\":42,\"caption\":\"Zeitenspiegel Reportagen Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Zeitenspiegel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zeitenspiegel\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#webpage\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/\",\"name\":\"Die Tr\\u00fcmmerm\\u00e4nner \\u2192 Zeitenspiegel Reportagen\",\"description\":\"Autor Carsten StormerErschienen in \\\"Neon\\\", 09\\\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\\u00e4mpfer zu retten, was nicht mehr zu retten ist.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cs_truemmermaenner_neon.jpg\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#mainImage\",\"width\":600,\"height\":406,\"caption\":\"Die Tr\\u00fcmmerm\\u00e4nner\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/projekte\\\/die-truemmermaenner\\\/#mainImage\"},\"datePublished\":\"2014-08-31T22:00:00+00:00\",\"dateModified\":\"2014-08-31T22:00:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/\",\"name\":\"Zeitenspiegel Reportagen\",\"alternateName\":\"Zeitenspiegel\",\"description\":\"Die Agentur f\\u00fcr Reportagen\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeitenspiegel.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen","description":"Autor Carsten StormerErschienen in \"Neon\", 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.","canonical_url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.zeitenspiegel.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","name":"Reportage"}},{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","position":2,"name":"Reportage","item":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#listItem","name":"Die Tr\u00fcmmerm\u00e4nner"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#listItem","position":3,"name":"Die Tr\u00fcmmerm\u00e4nner","previousItem":{"@type":"ListItem","@id":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/#listItem","name":"Reportage"}}]},{"@type":"Organization","@id":"https:\/\/www.zeitenspiegel.de\/en\/#organization","name":"Zeitenspiegel Reportagen","description":"Die Agentur f\u00fcr Reportagen","url":"https:\/\/www.zeitenspiegel.de\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#organizationLogo","width":516,"height":42,"caption":"Zeitenspiegel Reportagen Logo"},"image":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Zeitenspiegel\/","https:\/\/www.instagram.com\/zeitenspiegel\/"]},{"@type":"WebPage","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#webpage","url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/","name":"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen","description":"Autor Carsten StormerErschienen in \"Neon\", 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/07\/cs_truemmermaenner_neon.jpg","@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#mainImage","width":600,"height":406,"caption":"Die Tr\u00fcmmerm\u00e4nner"},"primaryImageOfPage":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/#mainImage"},"datePublished":"2014-08-31T22:00:00+00:00","dateModified":"2014-08-31T22:00:00+00:00"},{"@type":"WebSite","@id":"https:\/\/www.zeitenspiegel.de\/en\/#website","url":"https:\/\/www.zeitenspiegel.de\/en\/","name":"Zeitenspiegel Reportagen","alternateName":"Zeitenspiegel","description":"Die Agentur f\u00fcr Reportagen","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.zeitenspiegel.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Zeitenspiegel Reportagen \u2192 Die Agentur f\u00fcr Reportagen","og:type":"article","og:title":"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen","og:description":"Autor Carsten StormerErschienen in &quot;Neon&quot;, 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.","og:url":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/","og:image":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","og:image:secure_url":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg","og:image:width":517,"og:image:height":42,"article:published_time":"2014-08-31T22:00:00+00:00","article:modified_time":"2014-08-31T22:00:00+00:00","article:publisher":"https:\/\/www.facebook.com\/Zeitenspiegel\/","twitter:card":"summary_large_image","twitter:title":"Die Tr\u00fcmmerm\u00e4nner \u2192 Zeitenspiegel Reportagen","twitter:description":"Autor Carsten StormerErschienen in &quot;Neon&quot;, 09\/2014Millionen Syrer sind auf der Flucht. Doch was passiert mit denen, die blieben? In Aleppo versuchen ehemalige K\u00e4mpfer zu retten, was nicht mehr zu retten ist.","twitter:image":"https:\/\/www.zeitenspiegel.de\/wp-content\/uploads\/2025\/12\/zeitenspiegel-reportagen-logo.svg"},"aioseo_meta_data":{"post_id":"2857","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-09-27 11:22:33","updated":"2025-09-27 11:22:33","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.zeitenspiegel.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/\" title=\"Reportage\">Reportage<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDie Tr\u00fcmmerm\u00e4nner\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.zeitenspiegel.de\/en"},{"label":"Reportage","link":"https:\/\/www.zeitenspiegel.de\/en\/tag\/reportage\/"},{"label":"Die Tr\u00fcmmerm\u00e4nner","link":"https:\/\/www.zeitenspiegel.de\/en\/projekte\/die-truemmermaenner\/"}],"_links":{"self":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte\/2857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte"}],"about":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/types\/projekte"}],"version-history":[{"count":0,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/projekte\/2857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/media\/2858"}],"wp:attachment":[{"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/media?parent=2857"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zeitenspiegel.de\/en\/wp-json\/wp\/v2\/tags?post=2857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}